{"id":4,"date":"2016-05-05T00:37:42","date_gmt":"2016-05-05T03:37:42","guid":{"rendered":"http:\/\/localhost\/colegiosanrafael_wp\/?page_id=4"},"modified":"2026-04-08T16:43:53","modified_gmt":"2026-04-08T20:43:53","slug":"importante-13-79-27-2-18-2-2-2","status":"publish","type":"page","link":"https:\/\/www.colegiosanrafael.cl\/","title":{"rendered":"P\u00e1gina principal"},"content":{"rendered":"<div class=\"fusion-one-fourth fusion-layout-column fusion-column-inner-bg-wrapper fusion-spacing-yes\" style=\"margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-animated\" data-bg-url=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Valores-2026-300x300.png\" data-animationType=\"bounce\" data-animationDuration=\"0.1\" data-animationOffset=\"bottom-in-view\"><div class=\"fusion-clearfix\"><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-liftup\"><a ><span class=\"fusion-column-inner-bg-image\" style=\"background:url(https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Valores-2026-300x300.png) left top no-repeat ;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><div class=\"fusion-one-fourth fusion-layout-column fusion-column-inner-bg-wrapper fusion-spacing-yes\" style=\"margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-animated\" style=\"border:1px solid #31bece;\" data-bg-url=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/circulares-300x300.png\" data-animationType=\"zoomInDown\" data-animationDuration=\"0.1\" data-animationOffset=\"100%\"><div class=\"fusion-clearfix\"><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-liftup\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2022\/04\/11\/circulares\/\"><span class=\"fusion-column-inner-bg-image\" style=\"background:url(https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/circulares-300x300.png) left top no-repeat ;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><div class=\"fusion-one-fourth fusion-layout-column fusion-column-inner-bg-wrapper fusion-spacing-yes\" style=\"margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-animated\" style=\"border:1px solid #1e73be;\" data-bg-url=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2023\/07\/PASOS-300x300.png\" data-animationType=\"flash\" data-animationDuration=\"0.1\" data-animationOffset=\"100%\"><div class=\"fusion-clearfix\"><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-zoomin\"><a href=\"https:\/\/www.pasosuandes.cl\/\"><span class=\"fusion-column-inner-bg-image\" style=\"background:url(https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2023\/07\/PASOS-300x300.png) left top no-repeat ;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><div class=\"fusion-one-fourth fusion-layout-column fusion-column-inner-bg-wrapper fusion-column-last fusion-spacing-yes\" style=\"margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-animated\" style=\"border:2px solid #1e73be;\" data-bg-url=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/30anos-300x300.png\" data-animationType=\"slideInDown\" data-animationDuration=\"0.1\" data-animationOffset=\"100%\"><div class=\"fusion-clearfix\"><\/div><\/div><span class=\"fusion-column-inner-bg hover-type-liftup\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2023\/05\/05\/video_institucional\/\"><span class=\"fusion-column-inner-bg-image\" style=\"background:url(https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/30anos-300x300.png) left top no-repeat ;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"><\/span><\/a><\/span><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-fullwidth-1  fusion-parallax-fixed nonhundred-percent-fullwidth\" style=\"border-color:#eae9e9;border-bottom-width: 0px;border-top-width: 0px;border-bottom-style: dashed;border-top-style: dashed;padding-bottom:10px;padding-top:10px;padding-left:0px;padding-right:0px;background-color:rgba(255,255,255,0);\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-fullwidth-1 {\n                            padding-left: 0px !important;\n                            padding-right: 0px !important;\n                        }<\/style><div class=\"fusion-row\"><\/div><\/div><div class=\"fusion-one-fourth fusion-layout-column fusion-spacing-yes\" style=\"margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper\"><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-1 .fusion-button-text, .fusion-button.button-1 i {color:#ffffff;}.fusion-button.button-1 {border-width:2px;border-color:#ffffff;}.fusion-button.button-1 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-1:hover .fusion-button-text, .fusion-button.button-1:hover i,.fusion-button.button-1:focus .fusion-button-text, .fusion-button.button-1:focus i,.fusion-button.button-1:active .fusion-button-text, .fusion-button.button-1:active{color:#ffffff;}.fusion-button.button-1:hover, .fusion-button.button-1:focus, .fusion-button.button-1:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-1:hover .fusion-button-icon-divider, .fusion-button.button-1:hover .fusion-button-icon-divider, .fusion-button.button-1:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-1{background: #6b1703;}.fusion-button.button-1:hover,.button-1:focus,.fusion-button.button-1:active{background: #ffffff;}.fusion-button.button-1{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-1\" target=\"_blank\" href=\"https:\/\/www.e-mat.cl\/\"><i class=\"fa fa-graduation-cap button-icon-left\"><\/i><span class=\"fusion-button-text\">Compumat<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-2 .fusion-button-text, .fusion-button.button-2 i {color:#ffffff;}.fusion-button.button-2 {border-width:2px;border-color:#ffffff;}.fusion-button.button-2 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-2:hover .fusion-button-text, .fusion-button.button-2:hover i,.fusion-button.button-2:focus .fusion-button-text, .fusion-button.button-2:focus i,.fusion-button.button-2:active .fusion-button-text, .fusion-button.button-2:active{color:#ffffff;}.fusion-button.button-2:hover, .fusion-button.button-2:focus, .fusion-button.button-2:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-2:hover .fusion-button-icon-divider, .fusion-button.button-2:hover .fusion-button-icon-divider, .fusion-button.button-2:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-2{background: #03a536;}.fusion-button.button-2:hover,.button-2:focus,.fusion-button.button-2:active{background: #ffffff;}.fusion-button.button-2{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-2\" target=\"_blank\" href=\"https:\/\/www.puntajenacional.cl\/landing\/\"><i class=\"fa fa-graduation-cap button-icon-left\"><\/i><span class=\"fusion-button-text\">Puntaje Nacional<\/span><\/a><\/div>\nBorrado: <div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-3 .fusion-button-text, .fusion-button.button-3 i {color:#ffffff;}.fusion-button.button-3 {border-width:2px;border-color:#ffffff;}.fusion-button.button-3 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-3:hover .fusion-button-text, .fusion-button.button-3:hover i,.fusion-button.button-3:focus .fusion-button-text, .fusion-button.button-3:focus i,.fusion-button.button-3:active .fusion-button-text, .fusion-button.button-3:active{color:#ffffff;}.fusion-button.button-3:hover, .fusion-button.button-3:focus, .fusion-button.button-3:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-3:hover .fusion-button-icon-divider, .fusion-button.button-3:hover .fusion-button-icon-divider, .fusion-button.button-3:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-3{background: #6b1703;}.fusion-button.button-3:hover,.button-3:focus,.fusion-button.button-3:active{background: #ffffff;}.fusion-button.button-3{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-3\" target=\"_blank\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/contacto\/\"><i class=\"fa fa-graduation-cap button-icon-left\"><\/i><span class=\"fusion-button-text\">Trabaja con nosotros<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-4 .fusion-button-text, .fusion-button.button-4 i {color:#ffffff;}.fusion-button.button-4 {border-width:2px;border-color:#ffffff;}.fusion-button.button-4 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-4:hover .fusion-button-text, .fusion-button.button-4:hover i,.fusion-button.button-4:focus .fusion-button-text, .fusion-button.button-4:focus i,.fusion-button.button-4:active .fusion-button-text, .fusion-button.button-4:active{color:#ffffff;}.fusion-button.button-4:hover, .fusion-button.button-4:focus, .fusion-button.button-4:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-4:hover .fusion-button-icon-divider, .fusion-button.button-4:hover .fusion-button-icon-divider, .fusion-button.button-4:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-4{background: #03a536;}.fusion-button.button-4:hover,.button-4:focus,.fusion-button.button-4:active{background: #ffffff;}.fusion-button.button-4{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-4\" target=\"_blank\" href=\"http:\/\/www.colegiosanrafael.cl\/index.php\/blog\/\"><i class=\"fa fa-graduation-cap button-icon-left\"><\/i><span class=\"fusion-button-text\">Blogs<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-5 .fusion-button-text, .fusion-button.button-5 i {color:#ffffff;}.fusion-button.button-5 {border-width:2px;border-color:#ffffff;}.fusion-button.button-5 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-5:hover .fusion-button-text, .fusion-button.button-5:hover i,.fusion-button.button-5:focus .fusion-button-text, .fusion-button.button-5:focus i,.fusion-button.button-5:active .fusion-button-text, .fusion-button.button-5:active{color:#ffffff;}.fusion-button.button-5:hover, .fusion-button.button-5:focus, .fusion-button.button-5:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-5:hover .fusion-button-icon-divider, .fusion-button.button-5:hover .fusion-button-icon-divider, .fusion-button.button-5:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-5{background: #08cc9e;}.fusion-button.button-5:hover,.button-5:focus,.fusion-button.button-5:active{background: #e2eacc;\n\t\t\t\t\tbackground-image: -webkit-gradient( linear, left bottom, left top, from( #ffffff ), to( #e2eacc ) );\n\t\t\t\t\tbackground-image: -webkit-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image:\t-moz-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image:\t  -o-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image: linear-gradient( to top, #ffffff, #e2eacc );}.fusion-button.button-5{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-5\" target=\"_blank\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/convivencia-escolar\/\"><i class=\"fa fa-file-text-o button-icon-left\"><\/i><span class=\"fusion-button-text\">Convivencia Escolar<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-6 .fusion-button-text, .fusion-button.button-6 i {color:#ffffff;}.fusion-button.button-6 {border-width:2px;border-color:#ffffff;}.fusion-button.button-6 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-6:hover .fusion-button-text, .fusion-button.button-6:hover i,.fusion-button.button-6:focus .fusion-button-text, .fusion-button.button-6:focus i,.fusion-button.button-6:active .fusion-button-text, .fusion-button.button-6:active{color:#ffffff;}.fusion-button.button-6:hover, .fusion-button.button-6:focus, .fusion-button.button-6:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-6:hover .fusion-button-icon-divider, .fusion-button.button-6:hover .fusion-button-icon-divider, .fusion-button.button-6:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-6{background: #175366;}.fusion-button.button-6:hover,.button-6:focus,.fusion-button.button-6:active{background: #acb201;}.fusion-button.button-6{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-6\" target=\"_blank\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2021\/09\/01\/importante-13-79-21\/\"><i class=\"fa fa-list-alt button-icon-left\"><\/i><span class=\"fusion-button-text\">Calendario de Pruebas, 1\u00b0 Ciclo B\u00e1sico<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-7 .fusion-button-text, .fusion-button.button-7 i {color:#ffffff;}.fusion-button.button-7 {border-width:2px;border-color:#ffffff;}.fusion-button.button-7 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-7:hover .fusion-button-text, .fusion-button.button-7:hover i,.fusion-button.button-7:focus .fusion-button-text, .fusion-button.button-7:focus i,.fusion-button.button-7:active .fusion-button-text, .fusion-button.button-7:active{color:#ffffff;}.fusion-button.button-7:hover, .fusion-button.button-7:focus, .fusion-button.button-7:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-7:hover .fusion-button-icon-divider, .fusion-button.button-7:hover .fusion-button-icon-divider, .fusion-button.button-7:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-7{background: #01a070;}.fusion-button.button-7:hover,.button-7:focus,.fusion-button.button-7:active{background: #acb201;}.fusion-button.button-7{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-7\" target=\"_blank\" href=\"http:\/\/www.colegiosanrafael.cl\/index.php\/calendario\/\"><i class=\"fa fa-calendar-check-o button-icon-left\"><\/i><span class=\"fusion-button-text\">Calendario de Actividades<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-8 .fusion-button-text, .fusion-button.button-8 i {color:#ffffff;}.fusion-button.button-8 {border-width:2px;border-color:#ffffff;}.fusion-button.button-8 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-8:hover .fusion-button-text, .fusion-button.button-8:hover i,.fusion-button.button-8:focus .fusion-button-text, .fusion-button.button-8:focus i,.fusion-button.button-8:active .fusion-button-text, .fusion-button.button-8:active{color:#ffffff;}.fusion-button.button-8:hover, .fusion-button.button-8:focus, .fusion-button.button-8:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-8:hover .fusion-button-icon-divider, .fusion-button.button-8:hover .fusion-button-icon-divider, .fusion-button.button-8:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-8{background: #628227;}.fusion-button.button-8:hover,.button-8:focus,.fusion-button.button-8:active{background: #acb201;}.fusion-button.button-8{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-8\" target=\"_blank\"><i class=\"fa fa-check button-icon-left\"><\/i><span class=\"fusion-button-text\">Ingresar a Appoderado<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-9 .fusion-button-text, .fusion-button.button-9 i {color:#ffffff;}.fusion-button.button-9 {border-width:2px;border-color:#ffffff;}.fusion-button.button-9 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-9:hover .fusion-button-text, .fusion-button.button-9:hover i,.fusion-button.button-9:focus .fusion-button-text, .fusion-button.button-9:focus i,.fusion-button.button-9:active .fusion-button-text, .fusion-button.button-9:active{color:#ffffff;}.fusion-button.button-9:hover, .fusion-button.button-9:focus, .fusion-button.button-9:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-9:hover .fusion-button-icon-divider, .fusion-button.button-9:hover .fusion-button-icon-divider, .fusion-button.button-9:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-9{background: #60550d;}.fusion-button.button-9:hover,.button-9:focus,.fusion-button.button-9:active{background: #e9eadc;}.fusion-button.button-9{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-9\" target=\"_blank\" href=\"https:\/\/www.webpay.cl\/portalpagodirecto\/pages\/institucion.jsf?idEstablecimiento=171505\"><i class=\"fa fa-usd button-icon-left\"><\/i><span class=\"fusion-button-text\">WebPay<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-10 .fusion-button-text, .fusion-button.button-10 i {color:#ffffff;}.fusion-button.button-10 {border-width:2px;border-color:#ffffff;}.fusion-button.button-10 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-10:hover .fusion-button-text, .fusion-button.button-10:hover i,.fusion-button.button-10:focus .fusion-button-text, .fusion-button.button-10:focus i,.fusion-button.button-10:active .fusion-button-text, .fusion-button.button-10:active{color:#ffffff;}.fusion-button.button-10:hover, .fusion-button.button-10:focus, .fusion-button.button-10:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-10:hover .fusion-button-icon-divider, .fusion-button.button-10:hover .fusion-button-icon-divider, .fusion-button.button-10:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-10{background: #107214;}.fusion-button.button-10:hover,.button-10:focus,.fusion-button.button-10:active{background: #e8e7d5;}.fusion-button.button-10{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-10\" target=\"_blank\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/finanzas\/\"><i class=\"fa fa-usd button-icon-left\"><\/i><span class=\"fusion-button-text\">Finanzas<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-11 .fusion-button-text, .fusion-button.button-11 i {color:#ffffff;}.fusion-button.button-11 {border-width:2px;border-color:#ffffff;}.fusion-button.button-11 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-11:hover .fusion-button-text, .fusion-button.button-11:hover i,.fusion-button.button-11:focus .fusion-button-text, .fusion-button.button-11:focus i,.fusion-button.button-11:active .fusion-button-text, .fusion-button.button-11:active{color:#ffffff;}.fusion-button.button-11:hover, .fusion-button.button-11:focus, .fusion-button.button-11:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-11:hover .fusion-button-icon-divider, .fusion-button.button-11:hover .fusion-button-icon-divider, .fusion-button.button-11:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-11{background: #0c663c;}.fusion-button.button-11:hover,.button-11:focus,.fusion-button.button-11:active{background: #acb201;}.fusion-button.button-11{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-11\" target=\"_blank\" href=\"https:\/\/www.curriculumnacional.cl\/estudiante\/621\/w3-propertyname-822.html\"><i class=\"fa fa-file-o button-icon-left\"><\/i><span class=\"fusion-button-text\">Portal Aprendo en L\u00ednea \/ MINEDUC<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-12 .fusion-button-text, .fusion-button.button-12 i {color:#ffffff;}.fusion-button.button-12 {border-width:2px;border-color:#ffffff;}.fusion-button.button-12 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-12:hover .fusion-button-text, .fusion-button.button-12:hover i,.fusion-button.button-12:focus .fusion-button-text, .fusion-button.button-12:focus i,.fusion-button.button-12:active .fusion-button-text, .fusion-button.button-12:active{color:#ffffff;}.fusion-button.button-12:hover, .fusion-button.button-12:focus, .fusion-button.button-12:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-12:hover .fusion-button-icon-divider, .fusion-button.button-12:hover .fusion-button-icon-divider, .fusion-button.button-12:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-12{background: #0c7a60;}.fusion-button.button-12:hover,.button-12:focus,.fusion-button.button-12:active{background: #e8fcae;}.fusion-button.button-12{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-12\" target=\"_blank\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/tramites\/\"><i class=\"fa fa-wpforms button-icon-left\"><\/i><span class=\"fusion-button-text\">Tr\u00e1mites Online<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-13 .fusion-button-text, .fusion-button.button-13 i {color:#ffffff;}.fusion-button.button-13 {border-width:2px;border-color:#ffffff;}.fusion-button.button-13 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-13:hover .fusion-button-text, .fusion-button.button-13:hover i,.fusion-button.button-13:focus .fusion-button-text, .fusion-button.button-13:focus i,.fusion-button.button-13:active .fusion-button-text, .fusion-button.button-13:active{color:#ffffff;}.fusion-button.button-13:hover, .fusion-button.button-13:focus, .fusion-button.button-13:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-13:hover .fusion-button-icon-divider, .fusion-button.button-13:hover .fusion-button-icon-divider, .fusion-button.button-13:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-13{background: #536006;}.fusion-button.button-13:hover,.button-13:focus,.fusion-button.button-13:active{background: #e2eacc;\n\t\t\t\t\tbackground-image: -webkit-gradient( linear, left bottom, left top, from( #ffffff ), to( #e2eacc ) );\n\t\t\t\t\tbackground-image: -webkit-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image:\t-moz-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image:\t  -o-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image: linear-gradient( to top, #ffffff, #e2eacc );}.fusion-button.button-13{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-13\" target=\"_blank\" href=\"https:\/\/www.flipsnack.com\/UCECSRA\/revista-uce-csra-u56pvdblqb.html\"><i class=\"fa fa-file-text-o button-icon-left\"><\/i><span class=\"fusion-button-text\">Revista Cient\u00edfica Escolar<\/span><\/a><\/div><div class=\"fusion-button-wrapper\"><style type=\"text\/css\" scoped=\"scoped\">.fusion-button.button-14 .fusion-button-text, .fusion-button.button-14 i {color:#ffffff;}.fusion-button.button-14 {border-width:2px;border-color:#ffffff;}.fusion-button.button-14 .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-14:hover .fusion-button-text, .fusion-button.button-14:hover i,.fusion-button.button-14:focus .fusion-button-text, .fusion-button.button-14:focus i,.fusion-button.button-14:active .fusion-button-text, .fusion-button.button-14:active{color:#ffffff;}.fusion-button.button-14:hover, .fusion-button.button-14:focus, .fusion-button.button-14:active{border-width:2px;border-color:#ffffff;}.fusion-button.button-14:hover .fusion-button-icon-divider, .fusion-button.button-14:hover .fusion-button-icon-divider, .fusion-button.button-14:active .fusion-button-icon-divider{border-color:#ffffff;}.fusion-button.button-14{background: #07ba78;}.fusion-button.button-14:hover,.button-14:focus,.fusion-button.button-14:active{background: #e2eacc;\n\t\t\t\t\tbackground-image: -webkit-gradient( linear, left bottom, left top, from( #ffffff ), to( #e2eacc ) );\n\t\t\t\t\tbackground-image: -webkit-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image:\t-moz-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image:\t  -o-linear-gradient( bottom, #ffffff, #e2eacc );\n\t\t\t\t\tbackground-image: linear-gradient( to top, #ffffff, #e2eacc );}.fusion-button.button-14{width:100%;}<\/style><a class=\"fusion-button button-flat button-round button-xlarge button-custom button-14\" target=\"_blank\" href=\"https:\/\/www.sistemadeadmisionescolar.cl\"><i class=\"fa fa-file-text-o button-icon-left\"><\/i><span class=\"fusion-button-text\">Postulaci\u00f3n a Lista de Espera<\/span><\/a><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-three-fourth fusion-layout-column fusion-column-last fusion-spacing-yes\" style=\"margin-top:0px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper\"><div class=\"fusion-title title fusion-title-size-two\" style=\"margin-top:0px;margin-bottom:31px;\"><h2 class=\"title-heading-left\">Noticias y\/o Actividades<\/h2><div class=\"title-sep-container\"><div class=\"title-sep sep-double\"><\/div><\/div><\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-pagination\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:20px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -20px !important; margin-right:-20px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-pagination fusion-blog-layout-grid fusion-blog-layout-grid-3 isotope\" data-pages=\"9\" data-grid-col-space=\"40\" style=\"margin: -20px -20px 0;height:500px;\"><div id=\"post-12753\" class=\"fusion-post-grid post-12753 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1200\" height=\"1600\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-15.31.22.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-15.31.22-200x267.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-15.31.22-400x533.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-15.31.22-600x800.jpeg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-15.31.22-800x1067.jpeg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-15.31.22.jpeg 1200w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/05\/07\/csra-21-121\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-07-at-15.31.22.jpeg\" data-id=\"12753\" data-rel=\"iLightbox[gallery]\" data-title=\"WhatsApp Image 2026-05-07 at 15.31.22\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/05\/07\/csra-21-121\/\" target=\"_blank\">\n\t\t\t\t\tActo acad\u00e9mico 4\u00b0 b\u00e1sicos \u00abD\u00eda del Carabinero\u00bb\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/05\/07\/csra-21-121\/\" target=\"_blank\">Acto acad\u00e9mico 4\u00b0 b\u00e1sicos \u00abD\u00eda del Carabinero\u00bb<\/a><\/h2><div class=\"fusion-post-content-container\"><p>\"Servir con honor, proteger con valent\u00eda y cuidar a los [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12747\" class=\"fusion-post-grid post-12747 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1275\" height=\"1650\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1-200x259.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1-400x518.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1-600x776.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1-800x1035.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1-1200x1553.jpg 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1.jpg 1275w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/05\/04\/circular5\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1.jpg\" data-id=\"12747\" data-rel=\"iLightbox[gallery]\" data-title=\"1\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/05\/04\/circular5\/\" target=\"_blank\">\n\t\t\t\t\tCircular N\u00b05: D\u00eda del Estudiante(Cambio de fecha para el lunes 11 de mayo)\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/05\/04\/circular5\/\" target=\"_blank\">Circular N\u00b05: D\u00eda del Estudiante(Cambio de fecha para el lunes 11 de mayo)<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12592\" class=\"fusion-post-grid post-12592 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1024\" height=\"1280\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1-200x250.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1-400x500.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1-600x750.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1-800x1000.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1.jpg 1024w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/30\/csra-21-107\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1.jpg\" data-id=\"12592\" data-rel=\"iLightbox[gallery]\" data-title=\"1\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/30\/csra-21-107\/\" target=\"_blank\">\n\t\t\t\t\tReuniones de Apoderados: Mayo\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/30\/csra-21-107\/\" target=\"_blank\">Reuniones de Apoderados: Mayo<\/a><\/h2><div class=\"fusion-post-content-container\"><p> <\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12731\" class=\"fusion-post-grid post-12731 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1080\" height=\"1080\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/circulares.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/circulares-200x200.png 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/circulares-400x400.png 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/circulares-600x600.png 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/circulares-800x800.png 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/circulares.png 1080w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/29\/csra-21-120\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/circulares.png\" data-id=\"12731\" data-rel=\"iLightbox[gallery]\" data-title=\"circulares\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/29\/csra-21-120\/\" target=\"_blank\">\n\t\t\t\t\tImportante:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/29\/csra-21-120\/\" target=\"_blank\">Importante:<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12727\" class=\"fusion-post-grid post-12727 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"480\" height=\"640\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.39-1.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.39-1-200x267.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.39-1-400x533.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.39-1.jpeg 480w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/28\/csra-21-119\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.39-1.jpeg\" data-id=\"12727\" data-rel=\"iLightbox[gallery]\" data-title=\"WhatsApp Image 2026-04-29 at 15.15.39 (1)\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/28\/csra-21-119\/\" target=\"_blank\">\n\t\t\t\t\tJornada Pasos:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/28\/csra-21-119\/\" target=\"_blank\">Jornada Pasos:<\/a><\/h2><div class=\"fusion-post-content-container\"><p>En el consejo de profesores, nuestros docentes tuvieron la oportunidad [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12719\" class=\"fusion-post-grid post-12719 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"453\" height=\"640\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.37-1.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.37-1-200x283.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.37-1-400x565.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.37-1.jpeg 453w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/28\/csra-21-118\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-29-at-15.15.37-1.jpeg\" data-id=\"12719\" data-rel=\"iLightbox[gallery]\" data-title=\"WhatsApp Image 2026-04-29 at 15.15.37 (1)\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/28\/csra-21-118\/\" target=\"_blank\">\n\t\t\t\t\tJornada Nacional del D\u00eda de la Convivencia Escolar:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/28\/csra-21-118\/\" target=\"_blank\">Jornada Nacional del D\u00eda de la Convivencia Escolar:<\/a><\/h2><div class=\"fusion-post-content-container\"><p>Este martes celebramos esta fecha con una actividad destinada a [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12684\" class=\"fusion-post-grid post-12684 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1200\" height=\"1600\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-24-at-15.37.51-11.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-24-at-15.37.51-11-200x267.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-24-at-15.37.51-11-400x533.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-24-at-15.37.51-11-600x800.jpeg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-24-at-15.37.51-11-800x1067.jpeg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-24-at-15.37.51-11.jpeg 1200w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/24\/csra-21-116\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-24-at-15.37.51-11.jpeg\" data-id=\"12684\" data-rel=\"iLightbox[gallery]\" data-title=\"WhatsApp Image 2026-04-24 at 15.37.51 (11)\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/24\/csra-21-116\/\" target=\"_blank\">\n\t\t\t\t\tCelebraci\u00f3n del D\u00eda del Libro en el Colegio San Rafael Arc\u00e1ngel: 30 A\u00f1os Fomentando la Lectura\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/24\/csra-21-116\/\" target=\"_blank\">Celebraci\u00f3n del D\u00eda del Libro en el Colegio San Rafael Arc\u00e1ngel: 30 A\u00f1os Fomentando la Lectura<\/a><\/h2><div class=\"fusion-post-content-container\"><p>El Colegio San Rafael Arc\u00e1ngel se enorgullece en celebrar 30 [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12688\" class=\"fusion-post-grid post-12688 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"360\" height=\"480\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1-200x267.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1.jpeg 360w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/22\/csra-21-117\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/1.jpeg\" data-id=\"12688\" data-rel=\"iLightbox[gallery]\" data-title=\"1\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/22\/csra-21-117\/\" target=\"_blank\">\n\t\t\t\t\tJornada PME:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/22\/csra-21-117\/\" target=\"_blank\">Jornada PME:<\/a><\/h2><div class=\"fusion-post-content-container\"><p>Durante esta tarde se realiz\u00f3 la Jornada de Reflexi\u00f3n PME, [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12668\" class=\"fusion-post-grid post-12668 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"684\" height=\"392\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/tierra.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/tierra-200x115.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/tierra-400x229.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/tierra-600x344.jpeg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/tierra.jpeg 684w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/22\/csra-21-115\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/tierra.jpeg\" data-id=\"12668\" data-rel=\"iLightbox[gallery]\" data-title=\"tierra\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/22\/csra-21-115\/\" target=\"_blank\">\n\t\t\t\t\t22 de abril: \u00abD\u00eda Internacional de la Tierra\u00bb\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/22\/csra-21-115\/\" target=\"_blank\">22 de abril: \u00abD\u00eda Internacional de la Tierra\u00bb<\/a><\/h2><div class=\"fusion-post-content-container\"><p>En el marco del D\u00eda de la Tierra, y considerando [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12675\" class=\"fusion-post-grid post-12675 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1275\" height=\"1650\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04-200x259.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04-400x518.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04-600x776.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04-800x1035.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04-1200x1553.jpg 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04.jpg 1275w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/16\/circular4\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/Circular-N\u00b04.jpg\" data-id=\"12675\" data-rel=\"iLightbox[gallery]\" data-title=\"Circular N\u00b04\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/16\/circular4\/\" target=\"_blank\">\n\t\t\t\t\tCircular N\u00b04:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/16\/circular4\/\" target=\"_blank\">Circular N\u00b04:<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12674\" class=\"fusion-post-grid post-12674 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"180\" height=\"250\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/csra-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/15\/csra-21-114\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/csra-1.png\" data-id=\"12674\" data-rel=\"iLightbox[gallery]\" data-title=\"csra\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/15\/csra-21-114\/\" target=\"_blank\">\n\t\t\t\t\tNuestro colegio, nuestro lugar seguro:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/15\/csra-21-114\/\" target=\"_blank\">Nuestro colegio, nuestro lugar seguro:<\/a><\/h2><div class=\"fusion-post-content-container\"><p>\ufeff<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12656\" class=\"fusion-post-grid post-12656 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"658\" height=\"552\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/recaudacion.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/recaudacion-200x168.png 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/recaudacion-400x336.png 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/recaudacion-600x503.png 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/recaudacion.png 658w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/13\/csra-21-113\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/recaudacion.png\" data-id=\"12656\" data-rel=\"iLightbox[gallery]\" data-title=\"recaudaci\u00f3n\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/13\/csra-21-113\/\" target=\"_blank\">\n\t\t\t\t\tRecordar:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/13\/csra-21-113\/\" target=\"_blank\">Recordar:<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12634\" class=\"fusion-post-grid post-12634 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"333\" height=\"728\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/educacionfisica-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/educacionfisica-1-200x437.png 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/educacionfisica-1.png 333w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/08\/csra-21-112\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/educacionfisica-1.png\" data-id=\"12634\" data-rel=\"iLightbox[gallery]\" data-title=\"educacionfisica (1)\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/08\/csra-21-112\/\" target=\"_blank\">\n\t\t\t\t\t08 de abril: D\u00eda Nacional de la Educaci\u00f3n F\u00edsica y Deporte Escolar\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/08\/csra-21-112\/\" target=\"_blank\">08 de abril: D\u00eda Nacional de la Educaci\u00f3n F\u00edsica y Deporte Escolar<\/a><\/h2><div class=\"fusion-post-content-container\"><p>En este d\u00eda especial, invitamos a toda la comunidad educativa [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12633\" class=\"fusion-post-grid post-12633 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1275\" height=\"1650\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026-200x259.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026-400x518.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026-600x776.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026-800x1035.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026-1200x1553.jpg 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026.jpg 1275w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/01\/jornada-institucional\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/04\/CircularN32026.jpg\" data-id=\"12633\" data-rel=\"iLightbox[gallery]\" data-title=\"CircularN32026\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/01\/jornada-institucional\/\" target=\"_blank\">\n\t\t\t\t\tCircular N\u00b03: Suspensi\u00f3n de Clases\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/01\/jornada-institucional\/\" target=\"_blank\">Circular N\u00b03: Suspensi\u00f3n de Clases<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12627\" class=\"fusion-post-grid post-12627 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1414\" height=\"2000\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1-200x283.png 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1-400x566.png 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1-600x849.png 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1-800x1132.png 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1-1200x1697.png 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1.png 1414w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/01\/csra-21-111\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Flyer-1.png\" data-id=\"12627\" data-rel=\"iLightbox[gallery]\" data-title=\"Flyer (1)\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/01\/csra-21-111\/\" target=\"_blank\">\n\t\t\t\t\tImportante:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/04\/01\/csra-21-111\/\" target=\"_blank\">Importante:<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12624\" class=\"fusion-post-grid post-12624 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1024\" height=\"1280\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-15.24.22.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-15.24.22-200x250.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-15.24.22-400x500.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-15.24.22-600x750.jpeg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-15.24.22-800x1000.jpeg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-15.24.22.jpeg 1024w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/31\/csra-21-110\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-31-at-15.24.22.jpeg\" data-id=\"12624\" data-rel=\"iLightbox[gallery]\" data-title=\"WhatsApp Image 2026-03-31 at 15.24.22\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/31\/csra-21-110\/\" target=\"_blank\">\n\t\t\t\t\tEstimadas familias Sanrafaelinas:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/31\/csra-21-110\/\" target=\"_blank\">Estimadas familias Sanrafaelinas:<\/a><\/h2><div class=\"fusion-post-content-container\"><p>Este jueves 02 de abril conmemoramos el D\u00eda Mundial de [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12614\" class=\"fusion-post-grid post-12614 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"910\" height=\"1280\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/imagen.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/imagen-200x281.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/imagen-400x563.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/imagen-600x844.jpeg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/imagen-800x1125.jpeg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/imagen.jpeg 910w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/31\/csra-21-109\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/imagen.jpeg\" data-id=\"12614\" data-rel=\"iLightbox[gallery]\" data-title=\"imagen\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/31\/csra-21-109\/\" target=\"_blank\">\n\t\t\t\t\tCRA informa:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/31\/csra-21-109\/\" target=\"_blank\">CRA informa:<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12607\" class=\"fusion-post-grid post-12607 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1275\" height=\"1650\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-200x259.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-400x518.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-600x776.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-800x1035.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1-1200x1553.jpg 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1.jpg 1275w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/27\/semana-santa-2\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1.jpg\" data-id=\"12607\" data-rel=\"iLightbox[gallery]\" data-title=\"1\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/27\/semana-santa-2\/\" target=\"_blank\">\n\t\t\t\t\tCircular N\u00b0 2: Semana Santa\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/27\/semana-santa-2\/\" target=\"_blank\">Circular N\u00b0 2: Semana Santa<\/a><\/h2><div class=\"fusion-post-content-container\"><p> <\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12599\" class=\"fusion-post-grid post-12599 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1240\" height=\"1754\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001-200x283.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001-400x566.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001-600x849.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001-800x1132.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001-1200x1697.jpg 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001.jpg 1240w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/23\/csra-21-108\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Afiche-2026_page-0001.jpg\" data-id=\"12599\" data-rel=\"iLightbox[gallery]\" data-title=\"Afiche 2026_page-0001\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/23\/csra-21-108\/\" target=\"_blank\">\n\t\t\t\t\tInformaci\u00f3n ACLE:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/23\/csra-21-108\/\" target=\"_blank\">Informaci\u00f3n ACLE:<\/a><\/h2><div class=\"fusion-post-content-container\"><p>  Cualquier duda del correo instutucional escribir a :\u00a0 [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12577\" class=\"fusion-post-grid post-12577 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"665\" height=\"352\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/foto.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/foto-200x106.png 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/foto-400x212.png 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/foto-600x318.png 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/foto.png 665w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/16\/csra-21-105\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/foto.png\" data-id=\"12577\" data-rel=\"iLightbox[gallery]\" data-title=\"foto\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/16\/csra-21-105\/\" target=\"_blank\">\n\t\t\t\t\t16 de Marzo: D\u00eda en Contra del Cyberbullying:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/16\/csra-21-105\/\" target=\"_blank\">16 de Marzo: D\u00eda en Contra del Cyberbullying:<\/a><\/h2><div class=\"fusion-post-content-container\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12581\" class=\"fusion-post-grid post-12581 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"225\" height=\"225\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/images.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/images-200x200.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/images.jpg 225w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/16\/csra-21-106\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/images.jpg\" data-id=\"12581\" data-rel=\"iLightbox[gallery]\" data-title=\"images\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/16\/csra-21-106\/\" target=\"_blank\">\n\t\t\t\t\t\u00a1Celebramos el D\u00eda de \u03c0!\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/16\/csra-21-106\/\" target=\"_blank\">\u00a1Celebramos el D\u00eda de \u03c0!<\/a><\/h2><div class=\"fusion-post-content-container\"><p>\ufeff Durante el segundo recreo del lunes 16 de marzo, [...]<\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12545\" class=\"fusion-post-grid post-12545 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1080\" height=\"1350\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1uno.jpeg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1uno-200x250.jpeg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1uno-400x500.jpeg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1uno-600x750.jpeg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1uno-800x1000.jpeg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1uno.jpeg 1080w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/12\/pme\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/1uno.jpeg\" data-id=\"12545\" data-rel=\"iLightbox[gallery]\" data-title=\"1uno\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/12\/pme\/\" target=\"_blank\">\n\t\t\t\t\tInformaci\u00f3n Jornada PME:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/12\/pme\/\" target=\"_blank\">Informaci\u00f3n Jornada PME:<\/a><\/h2><div class=\"fusion-post-content-container\"><p> <\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12538\" class=\"fusion-post-grid post-12538 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"736\" height=\"1104\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/17412590897959.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/17412590897959-200x300.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/17412590897959-400x600.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/17412590897959-600x900.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/17412590897959.jpg 736w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/08\/csra-21-104\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/17412590897959.jpg\" data-id=\"12538\" data-rel=\"iLightbox[gallery]\" data-title=\"17412590897959\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/08\/csra-21-104\/\" target=\"_blank\">\n\t\t\t\t\t8 de Marzo, D\u00eda de la Mujer:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/08\/csra-21-104\/\" target=\"_blank\">8 de Marzo, D\u00eda de la Mujer:<\/a><\/h2><div class=\"fusion-post-content-container\"><p> <\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12498\" class=\"fusion-post-grid post-12498 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1275\" height=\"1650\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001-200x259.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001-400x518.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001-600x776.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001-800x1035.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001-1200x1553.jpg 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001.jpg 1275w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/05\/circular1\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/Circular-N\u00b01-2026_page-0001.jpg\" data-id=\"12498\" data-rel=\"iLightbox[gallery]\" data-title=\"Circular N\u00b01 2026_page-0001\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/05\/circular1\/\" target=\"_blank\">\n\t\t\t\t\tCircular N\u00b01  2026:\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/05\/circular1\/\" target=\"_blank\">Circular N\u00b01  2026:<\/a><\/h2><div class=\"fusion-post-content-container\"><p> <\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div id=\"post-12537\" class=\"fusion-post-grid post-12537 post type-post status-publish format-gallery has-post-thumbnail hentry category-noticia post_format-post-format-gallery\">\n<div class=\"fusion-post-wrapper\">\n\n\n\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li>\n<div class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\n\t\n\t\t\n\t\t\t\t\t<img width=\"1949\" height=\"1276\" src=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001-200x131.jpg 200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001-400x262.jpg 400w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001-600x393.jpg 600w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001-800x524.jpg 800w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001-1200x786.jpg 1200w, https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001.jpg 1949w\" sizes=\"(min-width: 784px) 340px, (min-width: 712px) 510px, (min-width: 640px) 712px, 100vw\" \/>\n\t\n\n\t\t<div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-link\" href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/03\/csra-21-103\/\" target=\"_blank\">Permalink<\/a>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"fusion-rollover-sep\"><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"fusion-rollover-gallery\" href=\"https:\/\/www.colegiosanrafael.cl\/wp-content\/uploads\/2026\/03\/LISTA-DE-UTILES-8\u00b0-BASICO-2026_page-0001.jpg\" data-id=\"12537\" data-rel=\"iLightbox[gallery]\" data-title=\"LISTA DE UTILES 8\u00b0 BASICO 2026_page-0001\" data-caption=\"\">\n\t\t\t\t\t\tGallery\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<h4 class=\"fusion-rollover-title\">\n\t\t\t\t<a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/03\/csra-21-103\/\" target=\"_blank\">\n\t\t\t\t\tLista de \u00datiles Escolares 2026 : 5\u00b0 a  8\u00b0 B\u00e1sico\t\t\t\t<\/a>\n\t\t\t<\/h4>\n\t\t\n\t\t\t\t\t\t\t\n\t\t\t<div class=\"fusion-rollover-categories\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/category\/noticia\/\" rel=\"tag\">Noticia<\/a><\/div>\t\t\n\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t<\/div>\n<\/div>\n\n\t\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n<div class=\"fusion-post-content-wrapper\"><div class=\"fusion-post-content post-content\"><h2 class=\"entry-title\"><a href=\"https:\/\/www.colegiosanrafael.cl\/index.php\/2026\/03\/03\/csra-21-103\/\" target=\"_blank\">Lista de \u00datiles Escolares 2026 : 5\u00b0 a  8\u00b0 B\u00e1sico<\/a><\/h2><div class=\"fusion-post-content-container\"><p> <\/p><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/div>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":[],"_links":{"self":[{"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/pages\/4"}],"collection":[{"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/comments?post=4"}],"version-history":[{"count":328,"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/pages\/4\/revisions"}],"predecessor-version":[{"id":12650,"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/pages\/4\/revisions\/12650"}],"wp:attachment":[{"href":"https:\/\/www.colegiosanrafael.cl\/index.php\/wp-json\/wp\/v2\/media?parent=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}